{"id":153595,"date":"2022-10-17T15:14:21","date_gmt":"2022-10-17T05:14:21","guid":{"rendered":"https:\/\/sandbox.smec-cloud.net\/desarrollo-internacional\/desarrollo-social-y-resiliencia-climatica\/"},"modified":"2022-10-17T15:14:21","modified_gmt":"2022-10-17T05:14:21","slug":"desarrollo-social-y-resiliencia-climatica","status":"publish","type":"page","link":"https:\/\/smec-archive.ns41.momentumdns.com\/sp_cl\/desarrollo-internacional\/desarrollo-social-y-resiliencia-climatica\/","title":{"rendered":"Desarrollo social y resiliencia clim\u00e1tica"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":153538,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-153595","page","type-page","status-publish","hentry"],"acf":[],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Desarrollo social y resiliencia clim\u00e1tica | SMEC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/smec-archive.ns41.momentumdns.com\/sp_cl\/desarrollo-internacional\/desarrollo-social-y-resiliencia-climatica\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Desarrollo social y resiliencia clim\u00e1tica | SMEC\" \/>\n<meta property=\"og:url\" content=\"https:\/\/smec-archive.ns41.momentumdns.com\/sp_cl\/desarrollo-internacional\/desarrollo-social-y-resiliencia-climatica\/\" \/>\n<meta property=\"og:site_name\" content=\"SMEC\" \/>\n<meta property=\"og:image\" content=\"https:\/\/smec-archive.ns41.momentumdns.com\/wp-content\/uploads\/2022\/11\/generic.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"818\" \/>\n\t<meta property=\"og:image:height\" content=\"495\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/smec-archive.ns41.momentumdns.com\/sp_cl\/desarrollo-internacional\/desarrollo-social-y-resiliencia-climatica\/\",\"url\":\"https:\/\/smec-archive.ns41.momentumdns.com\/sp_cl\/desarrollo-internacional\/desarrollo-social-y-resiliencia-climatica\/\",\"name\":\"Desarrollo social y resiliencia clim\u00e1tica | SMEC\",\"isPartOf\":{\"@id\":\"https:\/\/smec-archive.ns41.momentumdns.com\/#website\"},\"datePublished\":\"2022-10-17T05:14:21+00:00\",\"dateModified\":\"2022-10-17T05:14:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/smec-archive.ns41.momentumdns.com\/sp_cl\/desarrollo-internacional\/desarrollo-social-y-resiliencia-climatica\/#breadcrumb\"},\"inLanguage\":\"es-cl\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/smec-archive.ns41.momentumdns.com\/sp_cl\/desarrollo-internacional\/desarrollo-social-y-resiliencia-climatica\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/smec-archive.ns41.momentumdns.com\/sp_cl\/desarrollo-internacional\/desarrollo-social-y-resiliencia-climatica\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/smec-archive.ns41.momentumdns.com\/sp_cl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Desarrollo internacional\",\"item\":\"https:\/\/smec-archive.ns41.momentumdns.com\/sp_cl\/desarrollo-internacional\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Desarrollo social y resiliencia clim\u00e1tica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/smec-archive.ns41.momentumdns.com\/#website\",\"url\":\"https:\/\/smec-archive.ns41.momentumdns.com\/\",\"name\":\"SMEC\",\"description\":\"Global engineering consultancy\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/smec-archive.ns41.momentumdns.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-cl\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Desarrollo social y resiliencia clim\u00e1tica | SMEC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/smec-archive.ns41.momentumdns.com\/sp_cl\/desarrollo-internacional\/desarrollo-social-y-resiliencia-climatica\/","og_locale":"es_ES","og_type":"article","og_title":"Desarrollo social y resiliencia clim\u00e1tica | SMEC","og_url":"https:\/\/smec-archive.ns41.momentumdns.com\/sp_cl\/desarrollo-internacional\/desarrollo-social-y-resiliencia-climatica\/","og_site_name":"SMEC","og_image":[{"width":818,"height":495,"url":"https:\/\/smec-archive.ns41.momentumdns.com\/wp-content\/uploads\/2022\/11\/generic.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/smec-archive.ns41.momentumdns.com\/sp_cl\/desarrollo-internacional\/desarrollo-social-y-resiliencia-climatica\/","url":"https:\/\/smec-archive.ns41.momentumdns.com\/sp_cl\/desarrollo-internacional\/desarrollo-social-y-resiliencia-climatica\/","name":"Desarrollo social y resiliencia clim\u00e1tica | SMEC","isPartOf":{"@id":"https:\/\/smec-archive.ns41.momentumdns.com\/#website"},"datePublished":"2022-10-17T05:14:21+00:00","dateModified":"2022-10-17T05:14:21+00:00","breadcrumb":{"@id":"https:\/\/smec-archive.ns41.momentumdns.com\/sp_cl\/desarrollo-internacional\/desarrollo-social-y-resiliencia-climatica\/#breadcrumb"},"inLanguage":"es-cl","potentialAction":[{"@type":"ReadAction","target":["https:\/\/smec-archive.ns41.momentumdns.com\/sp_cl\/desarrollo-internacional\/desarrollo-social-y-resiliencia-climatica\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/smec-archive.ns41.momentumdns.com\/sp_cl\/desarrollo-internacional\/desarrollo-social-y-resiliencia-climatica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/smec-archive.ns41.momentumdns.com\/sp_cl\/"},{"@type":"ListItem","position":2,"name":"Desarrollo internacional","item":"https:\/\/smec-archive.ns41.momentumdns.com\/sp_cl\/desarrollo-internacional\/"},{"@type":"ListItem","position":3,"name":"Desarrollo social y resiliencia clim\u00e1tica"}]},{"@type":"WebSite","@id":"https:\/\/smec-archive.ns41.momentumdns.com\/#website","url":"https:\/\/smec-archive.ns41.momentumdns.com\/","name":"SMEC","description":"Global engineering consultancy","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/smec-archive.ns41.momentumdns.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-cl"}]}},"_links":{"self":[{"href":"https:\/\/smec-archive.ns41.momentumdns.com\/sp_cl\/wp-json\/wp\/v2\/pages\/153595","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/smec-archive.ns41.momentumdns.com\/sp_cl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/smec-archive.ns41.momentumdns.com\/sp_cl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/smec-archive.ns41.momentumdns.com\/sp_cl\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/smec-archive.ns41.momentumdns.com\/sp_cl\/wp-json\/wp\/v2\/comments?post=153595"}],"version-history":[{"count":0,"href":"https:\/\/smec-archive.ns41.momentumdns.com\/sp_cl\/wp-json\/wp\/v2\/pages\/153595\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/smec-archive.ns41.momentumdns.com\/sp_cl\/wp-json\/wp\/v2\/pages\/153538"}],"wp:attachment":[{"href":"https:\/\/smec-archive.ns41.momentumdns.com\/sp_cl\/wp-json\/wp\/v2\/media?parent=153595"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}